{"id":35941,"date":"2016-04-13T15:14:58","date_gmt":"2016-04-13T18:14:58","modified":"2016-04-19T08:32:43","modified_gmt":"2016-04-19T11:32:43","slug":"voce-esta-me-ouvindo","status":"publish","type":"post","link":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/","title":{"rendered":"Voc\u00ea est\u00e1 me ouvindo?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":76,"featured_media":35962,"comment_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"xtt-pa-colecoes":[],"xtt-pa-editorias":[414],"xtt-pa-departamentos":[17],"xtt-pa-projetos":[],"xtt-pa-regiao":[47],"xtt-pa-sedes":[126,129,130,131,144,145,146,149,156,112],"xtt-pa-owner":[705],"class_list":["post-35941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","xtt-pa-editorias-comportamento","xtt-pa-departamentos-evangelismo","xtt-pa-regiao-brasil","xtt-pa-sedes-aes","xtt-pa-sedes-amc","xtt-pa-sedes-aml","xtt-pa-sedes-ams","xtt-pa-sedes-arc","xtt-pa-sedes-arf","xtt-pa-sedes-ars","xtt-pa-sedes-ases","xtt-pa-sedes-mmn","xtt-pa-sedes-useb","xtt-pa-owner-uniao-sudeste-brasileira"],"acf":{"video_url":"<iframe title=\"Voc\u00ea est\u00e1 me ouvindo?\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/dtVq22aWI8s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>","video_length":"213"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00eddeos Adventistas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adventistasbrasiloficial\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-13T18:14:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-19T11:32:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1899\" \/>\n\t<meta property=\"og:image:height\" content=\"729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francis Matos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iasd\" \/>\n<meta name=\"twitter:site\" content=\"@iasd\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francis Matos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\"},\"author\":{\"name\":\"Francis Matos\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050\"},\"headline\":\"Voc\u00ea est\u00e1 me ouvindo?\",\"datePublished\":\"2016-04-13T18:14:58+00:00\",\"dateModified\":\"2016-04-19T11:32:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\"},\"wordCount\":4,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\",\"url\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\",\"name\":\"Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas\",\"isPartOf\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg\",\"datePublished\":\"2016-04-13T18:14:58+00:00\",\"dateModified\":\"2016-04-19T11:32:43+00:00\",\"author\":{\"@id\":\"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage\",\"url\":\"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg\",\"contentUrl\":\"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg\",\"width\":1899,\"height\":729},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/#website\",\"url\":\"https:\/\/videos.adventistas.org\/pt\/\",\"name\":\"V\u00eddeos Adventistas\",\"description\":\"Divis\u00e3o Sul-Americana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/videos.adventistas.org\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050\",\"name\":\"Francis Matos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g\",\"caption\":\"Francis Matos\"},\"description\":\"Formada em Jornalismo pela Universidade de Santo Amaro\/SP, com p\u00f3s gradua\u00e7\u00e3o em Comunica\u00e7\u00e3o Corporativa pelo Unasp.\",\"sameAs\":[\"http:\/\/www.useb.org.br\"],\"url\":\"https:\/\/videos.adventistas.org\/pt\/author\/francis-matos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/","og_locale":"pt_BR","og_type":"article","og_title":"Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas","og_url":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/","og_site_name":"V\u00eddeos Adventistas","article_publisher":"https:\/\/www.facebook.com\/adventistasbrasiloficial","article_published_time":"2016-04-13T18:14:58+00:00","article_modified_time":"2016-04-19T11:32:43+00:00","og_image":[{"width":1899,"height":729,"url":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","type":"image\/jpeg"}],"author":"Francis Matos","twitter_card":"summary_large_image","twitter_creator":"@iasd","twitter_site":"@iasd","twitter_misc":{"Escrito por":"Francis Matos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#article","isPartOf":{"@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/"},"author":{"name":"Francis Matos","@id":"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050"},"headline":"Voc\u00ea est\u00e1 me ouvindo?","datePublished":"2016-04-13T18:14:58+00:00","dateModified":"2016-04-19T11:32:43+00:00","mainEntityOfPage":{"@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/"},"wordCount":4,"commentCount":0,"image":{"@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage"},"thumbnailUrl":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/","url":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/","name":"Voc\u00ea est\u00e1 me ouvindo? - V\u00eddeos Adventistas","isPartOf":{"@id":"https:\/\/videos.adventistas.org\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage"},"image":{"@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage"},"thumbnailUrl":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","datePublished":"2016-04-13T18:14:58+00:00","dateModified":"2016-04-19T11:32:43+00:00","author":{"@id":"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/videos.adventistas.org\/pt\/editoria\/comportamento\/voce-esta-me-ouvindo\/#primaryimage","url":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","contentUrl":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","width":1899,"height":729},{"@type":"WebSite","@id":"https:\/\/videos.adventistas.org\/pt\/#website","url":"https:\/\/videos.adventistas.org\/pt\/","name":"V\u00eddeos Adventistas","description":"Divis\u00e3o Sul-Americana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/videos.adventistas.org\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/videos.adventistas.org\/pt\/#\/schema\/person\/5f60255db17ec266e929db4760f07050","name":"Francis Matos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4286a7c002c97b282bb3a57e1d2ff4441d40b65ab77c8eff917d1c0a58bcec96?s=96&d=mm&r=g","caption":"Francis Matos"},"description":"Formada em Jornalismo pela Universidade de Santo Amaro\/SP, com p\u00f3s gradua\u00e7\u00e3o em Comunica\u00e7\u00e3o Corporativa pelo Unasp.","sameAs":["http:\/\/www.useb.org.br"],"url":"https:\/\/videos.adventistas.org\/pt\/author\/francis-matos\/"}]}},"featured_media_url":{"full":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1.jpg","medium":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1-768x295.jpg","small":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1-240x135.jpg","pa-block-preview":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1-240x135.jpg","pa-block-render":"https:\/\/files.adventistas.org\/videos_v2\/pt\/2016\/04\/13181458\/voce-esta-me-ouvindo1-480x270.jpg"}}